{"id":1802,"date":"2026-05-19T11:42:07","date_gmt":"2026-05-19T09:42:07","guid":{"rendered":"https:\/\/www.stachristiana.at\/volksschule-rodaun\/?p=1802"},"modified":"2026-05-19T11:42:08","modified_gmt":"2026-05-19T09:42:08","slug":"rueckblick-2025-26-mit-erasmus-auf-entdeckungsreise-in-griechenland","status":"publish","type":"post","link":"https:\/\/www.stachristiana.at\/volksschule-rodaun\/news\/rueckblick-2025-26-mit-erasmus-auf-entdeckungsreise-in-griechenland.html","title":{"rendered":"R\u00fcckblick 2025\/26: Mit Erasmus+ auf Entdeckungsreise in Griechenland"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Im Schuljahr 2025\/26 machten sich die Lehrerinnen&nbsp;Manuela Schiller&nbsp;und&nbsp;Teresa Spiess&nbsp;gemeinsam mit unserem Native Speaker&nbsp;Paul Nelson&nbsp;im Rahmen des&nbsp;Erasmus+&nbsp;auf den Weg nach&nbsp;Thessaloniki.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Im Zuge eines Job Shadowings erhielten sie spannende Einblicke in den Schulalltag zweier Schulen vor Ort und konnten zahlreiche neue Eindr\u00fccke, Ideen und Unterrichtsmethoden kennenlernen. Besonders bereichernd waren die vielf\u00e4ltigen Impulse dazu, wie Fremdsprachenunterricht lebendig, praxisnah und kreativ in den Schulalltag integriert und umgesetzt werden kann.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ein besonderes Highlight war der gemeinsame Sportunterricht mit den Sch\u00fclerinnen und Sch\u00fclern vor Ort: Mit gro\u00dfer Begeisterung zeigten die Kinder traditionelle volkst\u00fcmliche T\u00e4nze wie den Sirtaki. Dabei wurden Kultur, Bewegung, Gemeinschaft und Freude auf wunderbare Weise miteinander verbunden.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Erasmusreise war eine wertvolle Erfahrung, aus der viele neue Ideen und Inspirationen f\u00fcr den eigenen Unterricht mitgenommen werden konnten. Internationale Begegnungen wie diese zeigen einmal mehr, wie wichtig Austausch, Offenheit und gemeinsames Lernen in Europa sind.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.stachristiana.at\/app\/uploads\/sites\/7\/2026\/05\/IMG_0155-1024x768.jpeg\" alt=\"\" class=\"wp-image-1809\" srcset=\"https:\/\/www.stachristiana.at\/app\/uploads\/sites\/7\/2026\/05\/IMG_0155-1024x768.jpeg 1024w, https:\/\/www.stachristiana.at\/app\/uploads\/sites\/7\/2026\/05\/IMG_0155-400x300.jpeg 400w, https:\/\/www.stachristiana.at\/app\/uploads\/sites\/7\/2026\/05\/IMG_0155-768x576.jpeg 768w, https:\/\/www.stachristiana.at\/app\/uploads\/sites\/7\/2026\/05\/IMG_0155-1536x1152.jpeg 1536w, https:\/\/www.stachristiana.at\/app\/uploads\/sites\/7\/2026\/05\/IMG_0155-2048x1536.jpeg 2048w, https:\/\/www.stachristiana.at\/app\/uploads\/sites\/7\/2026\/05\/IMG_0155-613x460.jpeg 613w, https:\/\/www.stachristiana.at\/app\/uploads\/sites\/7\/2026\/05\/IMG_0155-100x75.jpeg 100w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/www.stachristiana.at\/app\/uploads\/sites\/7\/2026\/05\/IMG_9965-768x1024.jpeg\" alt=\"\" class=\"wp-image-1808\" srcset=\"https:\/\/www.stachristiana.at\/app\/uploads\/sites\/7\/2026\/05\/IMG_9965-768x1024.jpeg 768w, https:\/\/www.stachristiana.at\/app\/uploads\/sites\/7\/2026\/05\/IMG_9965-300x400.jpeg 300w, https:\/\/www.stachristiana.at\/app\/uploads\/sites\/7\/2026\/05\/IMG_9965-1152x1536.jpeg 1152w, https:\/\/www.stachristiana.at\/app\/uploads\/sites\/7\/2026\/05\/IMG_9965-1536x2048.jpeg 1536w, https:\/\/www.stachristiana.at\/app\/uploads\/sites\/7\/2026\/05\/IMG_9965-345x460.jpeg 345w, https:\/\/www.stachristiana.at\/app\/uploads\/sites\/7\/2026\/05\/IMG_9965-56x75.jpeg 56w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.stachristiana.at\/app\/uploads\/sites\/7\/2026\/05\/IMG_0026-1024x768.jpeg\" alt=\"\" class=\"wp-image-1807\" srcset=\"https:\/\/www.stachristiana.at\/app\/uploads\/sites\/7\/2026\/05\/IMG_0026-1024x768.jpeg 1024w, https:\/\/www.stachristiana.at\/app\/uploads\/sites\/7\/2026\/05\/IMG_0026-400x300.jpeg 400w, https:\/\/www.stachristiana.at\/app\/uploads\/sites\/7\/2026\/05\/IMG_0026-768x576.jpeg 768w, https:\/\/www.stachristiana.at\/app\/uploads\/sites\/7\/2026\/05\/IMG_0026-1536x1152.jpeg 1536w, https:\/\/www.stachristiana.at\/app\/uploads\/sites\/7\/2026\/05\/IMG_0026-2048x1536.jpeg 2048w, https:\/\/www.stachristiana.at\/app\/uploads\/sites\/7\/2026\/05\/IMG_0026-613x460.jpeg 613w, https:\/\/www.stachristiana.at\/app\/uploads\/sites\/7\/2026\/05\/IMG_0026-100x75.jpeg 100w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Im Schuljahr 2025\/26 machten sich die Lehrerinnen&nbsp;Manuela Schiller&nbsp;und&nbsp;Teresa Spiess&nbsp;gemeinsam mit unserem Native Speaker&nbsp;Paul Nelson&nbsp;im Rahmen des&nbsp;Erasmus+&nbsp;auf den Weg nach&nbsp;Thessaloniki. Im Zuge eines Job Shadowings erhielten sie spannende Einblicke in den Schulalltag zweier Schulen vor Ort und konnten zahlreiche neue Eindr\u00fccke, Ideen und Unterrichtsmethoden kennenlernen. Besonders bereichernd waren die vielf\u00e4ltigen Impulse dazu, wie Fremdsprachenunterricht lebendig, praxisnah [&hellip;]<\/p>\n","protected":false},"author":79,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1802","post","type-post","status-publish","format-standard","hentry","category-news"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>R\u00fcckblick 2025\/26: Mit Erasmus+ auf Entdeckungsreise in Griechenland - Volksschule Rodaun<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.stachristiana.at\/volksschule-rodaun\/news\/rueckblick-2025-26-mit-erasmus-auf-entdeckungsreise-in-griechenland.html\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"R\u00fcckblick 2025\/26: Mit Erasmus+ auf Entdeckungsreise in Griechenland - Volksschule Rodaun\" \/>\n<meta property=\"og:description\" content=\"Im Schuljahr 2025\/26 machten sich die Lehrerinnen&nbsp;Manuela Schiller&nbsp;und&nbsp;Teresa Spiess&nbsp;gemeinsam mit unserem Native Speaker&nbsp;Paul Nelson&nbsp;im Rahmen des&nbsp;Erasmus+&nbsp;auf den Weg nach&nbsp;Thessaloniki. Im Zuge eines Job Shadowings erhielten sie spannende Einblicke in den Schulalltag zweier Schulen vor Ort und konnten zahlreiche neue Eindr\u00fccke, Ideen und Unterrichtsmethoden kennenlernen. Besonders bereichernd waren die vielf\u00e4ltigen Impulse dazu, wie Fremdsprachenunterricht lebendig, praxisnah [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.stachristiana.at\/volksschule-rodaun\/news\/rueckblick-2025-26-mit-erasmus-auf-entdeckungsreise-in-griechenland.html\" \/>\n<meta property=\"og:site_name\" content=\"Volksschule Rodaun\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-19T09:42:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-19T09:42:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.stachristiana.at\/app\/uploads\/sites\/7\/2026\/05\/IMG_0155-1024x768.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"teresaspiess\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"teresaspiess\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.stachristiana.at\\\/volksschule-rodaun\\\/news\\\/rueckblick-2025-26-mit-erasmus-auf-entdeckungsreise-in-griechenland.html#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.stachristiana.at\\\/volksschule-rodaun\\\/news\\\/rueckblick-2025-26-mit-erasmus-auf-entdeckungsreise-in-griechenland.html\"},\"author\":{\"name\":\"teresaspiess\",\"@id\":\"https:\\\/\\\/www.stachristiana.at\\\/volksschule-rodaun\\\/#\\\/schema\\\/person\\\/145981df32740f5ce76015703024cf57\"},\"headline\":\"R\u00fcckblick 2025\\\/26: Mit Erasmus+ auf Entdeckungsreise in Griechenland\",\"datePublished\":\"2026-05-19T09:42:07+00:00\",\"dateModified\":\"2026-05-19T09:42:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.stachristiana.at\\\/volksschule-rodaun\\\/news\\\/rueckblick-2025-26-mit-erasmus-auf-entdeckungsreise-in-griechenland.html\"},\"wordCount\":173,\"publisher\":{\"@id\":\"https:\\\/\\\/www.stachristiana.at\\\/volksschule-rodaun\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.stachristiana.at\\\/volksschule-rodaun\\\/news\\\/rueckblick-2025-26-mit-erasmus-auf-entdeckungsreise-in-griechenland.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.stachristiana.at\\\/app\\\/uploads\\\/sites\\\/7\\\/2026\\\/05\\\/IMG_0155-1024x768.jpeg\",\"articleSection\":[\"News\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.stachristiana.at\\\/volksschule-rodaun\\\/news\\\/rueckblick-2025-26-mit-erasmus-auf-entdeckungsreise-in-griechenland.html\",\"url\":\"https:\\\/\\\/www.stachristiana.at\\\/volksschule-rodaun\\\/news\\\/rueckblick-2025-26-mit-erasmus-auf-entdeckungsreise-in-griechenland.html\",\"name\":\"R\u00fcckblick 2025\\\/26: Mit Erasmus+ auf Entdeckungsreise in Griechenland - Volksschule Rodaun\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.stachristiana.at\\\/volksschule-rodaun\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.stachristiana.at\\\/volksschule-rodaun\\\/news\\\/rueckblick-2025-26-mit-erasmus-auf-entdeckungsreise-in-griechenland.html#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.stachristiana.at\\\/volksschule-rodaun\\\/news\\\/rueckblick-2025-26-mit-erasmus-auf-entdeckungsreise-in-griechenland.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.stachristiana.at\\\/app\\\/uploads\\\/sites\\\/7\\\/2026\\\/05\\\/IMG_0155-1024x768.jpeg\",\"datePublished\":\"2026-05-19T09:42:07+00:00\",\"dateModified\":\"2026-05-19T09:42:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.stachristiana.at\\\/volksschule-rodaun\\\/news\\\/rueckblick-2025-26-mit-erasmus-auf-entdeckungsreise-in-griechenland.html#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.stachristiana.at\\\/volksschule-rodaun\\\/news\\\/rueckblick-2025-26-mit-erasmus-auf-entdeckungsreise-in-griechenland.html\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.stachristiana.at\\\/volksschule-rodaun\\\/news\\\/rueckblick-2025-26-mit-erasmus-auf-entdeckungsreise-in-griechenland.html#primaryimage\",\"url\":\"https:\\\/\\\/www.stachristiana.at\\\/app\\\/uploads\\\/sites\\\/7\\\/2026\\\/05\\\/IMG_0155-1024x768.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.stachristiana.at\\\/app\\\/uploads\\\/sites\\\/7\\\/2026\\\/05\\\/IMG_0155-1024x768.jpeg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.stachristiana.at\\\/volksschule-rodaun\\\/news\\\/rueckblick-2025-26-mit-erasmus-auf-entdeckungsreise-in-griechenland.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Start\",\"item\":\"https:\\\/\\\/www.stachristiana.at\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"R\u00fcckblick 2025\\\/26: Mit Erasmus+ auf Entdeckungsreise in Griechenland\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.stachristiana.at\\\/volksschule-rodaun\\\/#website\",\"url\":\"https:\\\/\\\/www.stachristiana.at\\\/volksschule-rodaun\\\/\",\"name\":\"Sta. Christiana - Private Volksschule Rodaun\",\"description\":\"Schulen zum Leben\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.stachristiana.at\\\/volksschule-rodaun\\\/#organization\"},\"alternateName\":\"Sta. Christiana\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.stachristiana.at\\\/volksschule-rodaun\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.stachristiana.at\\\/volksschule-rodaun\\\/#organization\",\"name\":\"Sta. Christiana - Private Volksschule Rodaun\",\"alternateName\":\"Sta. Christiana\",\"url\":\"https:\\\/\\\/www.stachristiana.at\\\/volksschule-rodaun\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.stachristiana.at\\\/volksschule-rodaun\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.stachristiana.at\\\/app\\\/uploads\\\/sites\\\/7\\\/2022\\\/05\\\/logo-sta-christiana.png\",\"contentUrl\":\"https:\\\/\\\/www.stachristiana.at\\\/app\\\/uploads\\\/sites\\\/7\\\/2022\\\/05\\\/logo-sta-christiana.png\",\"width\":1200,\"height\":491,\"caption\":\"Sta. Christiana - Private Volksschule Rodaun\"},\"image\":{\"@id\":\"https:\\\/\\\/www.stachristiana.at\\\/volksschule-rodaun\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.stachristiana.at\\\/volksschule-rodaun\\\/#\\\/schema\\\/person\\\/145981df32740f5ce76015703024cf57\",\"name\":\"teresaspiess\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/07fb5e28c564dbade850e52239d0e4c0317f92215405dd0f28a0468c307ad1ac?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/07fb5e28c564dbade850e52239d0e4c0317f92215405dd0f28a0468c307ad1ac?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/07fb5e28c564dbade850e52239d0e4c0317f92215405dd0f28a0468c307ad1ac?s=96&d=mm&r=g\",\"caption\":\"teresaspiess\"},\"url\":\"https:\\\/\\\/www.stachristiana.at\\\/volksschule-rodaun\\\/author\\\/teresaspiess\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"R\u00fcckblick 2025\/26: Mit Erasmus+ auf Entdeckungsreise in Griechenland - Volksschule Rodaun","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.stachristiana.at\/volksschule-rodaun\/news\/rueckblick-2025-26-mit-erasmus-auf-entdeckungsreise-in-griechenland.html","og_locale":"de_DE","og_type":"article","og_title":"R\u00fcckblick 2025\/26: Mit Erasmus+ auf Entdeckungsreise in Griechenland - Volksschule Rodaun","og_description":"Im Schuljahr 2025\/26 machten sich die Lehrerinnen&nbsp;Manuela Schiller&nbsp;und&nbsp;Teresa Spiess&nbsp;gemeinsam mit unserem Native Speaker&nbsp;Paul Nelson&nbsp;im Rahmen des&nbsp;Erasmus+&nbsp;auf den Weg nach&nbsp;Thessaloniki. Im Zuge eines Job Shadowings erhielten sie spannende Einblicke in den Schulalltag zweier Schulen vor Ort und konnten zahlreiche neue Eindr\u00fccke, Ideen und Unterrichtsmethoden kennenlernen. Besonders bereichernd waren die vielf\u00e4ltigen Impulse dazu, wie Fremdsprachenunterricht lebendig, praxisnah [&hellip;]","og_url":"https:\/\/www.stachristiana.at\/volksschule-rodaun\/news\/rueckblick-2025-26-mit-erasmus-auf-entdeckungsreise-in-griechenland.html","og_site_name":"Volksschule Rodaun","article_published_time":"2026-05-19T09:42:07+00:00","article_modified_time":"2026-05-19T09:42:08+00:00","og_image":[{"width":1024,"height":768,"url":"https:\/\/www.stachristiana.at\/app\/uploads\/sites\/7\/2026\/05\/IMG_0155-1024x768.jpeg","type":"image\/jpeg"}],"author":"teresaspiess","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"teresaspiess","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.stachristiana.at\/volksschule-rodaun\/news\/rueckblick-2025-26-mit-erasmus-auf-entdeckungsreise-in-griechenland.html#article","isPartOf":{"@id":"https:\/\/www.stachristiana.at\/volksschule-rodaun\/news\/rueckblick-2025-26-mit-erasmus-auf-entdeckungsreise-in-griechenland.html"},"author":{"name":"teresaspiess","@id":"https:\/\/www.stachristiana.at\/volksschule-rodaun\/#\/schema\/person\/145981df32740f5ce76015703024cf57"},"headline":"R\u00fcckblick 2025\/26: Mit Erasmus+ auf Entdeckungsreise in Griechenland","datePublished":"2026-05-19T09:42:07+00:00","dateModified":"2026-05-19T09:42:08+00:00","mainEntityOfPage":{"@id":"https:\/\/www.stachristiana.at\/volksschule-rodaun\/news\/rueckblick-2025-26-mit-erasmus-auf-entdeckungsreise-in-griechenland.html"},"wordCount":173,"publisher":{"@id":"https:\/\/www.stachristiana.at\/volksschule-rodaun\/#organization"},"image":{"@id":"https:\/\/www.stachristiana.at\/volksschule-rodaun\/news\/rueckblick-2025-26-mit-erasmus-auf-entdeckungsreise-in-griechenland.html#primaryimage"},"thumbnailUrl":"https:\/\/www.stachristiana.at\/app\/uploads\/sites\/7\/2026\/05\/IMG_0155-1024x768.jpeg","articleSection":["News"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.stachristiana.at\/volksschule-rodaun\/news\/rueckblick-2025-26-mit-erasmus-auf-entdeckungsreise-in-griechenland.html","url":"https:\/\/www.stachristiana.at\/volksschule-rodaun\/news\/rueckblick-2025-26-mit-erasmus-auf-entdeckungsreise-in-griechenland.html","name":"R\u00fcckblick 2025\/26: Mit Erasmus+ auf Entdeckungsreise in Griechenland - Volksschule Rodaun","isPartOf":{"@id":"https:\/\/www.stachristiana.at\/volksschule-rodaun\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.stachristiana.at\/volksschule-rodaun\/news\/rueckblick-2025-26-mit-erasmus-auf-entdeckungsreise-in-griechenland.html#primaryimage"},"image":{"@id":"https:\/\/www.stachristiana.at\/volksschule-rodaun\/news\/rueckblick-2025-26-mit-erasmus-auf-entdeckungsreise-in-griechenland.html#primaryimage"},"thumbnailUrl":"https:\/\/www.stachristiana.at\/app\/uploads\/sites\/7\/2026\/05\/IMG_0155-1024x768.jpeg","datePublished":"2026-05-19T09:42:07+00:00","dateModified":"2026-05-19T09:42:08+00:00","breadcrumb":{"@id":"https:\/\/www.stachristiana.at\/volksschule-rodaun\/news\/rueckblick-2025-26-mit-erasmus-auf-entdeckungsreise-in-griechenland.html#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.stachristiana.at\/volksschule-rodaun\/news\/rueckblick-2025-26-mit-erasmus-auf-entdeckungsreise-in-griechenland.html"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.stachristiana.at\/volksschule-rodaun\/news\/rueckblick-2025-26-mit-erasmus-auf-entdeckungsreise-in-griechenland.html#primaryimage","url":"https:\/\/www.stachristiana.at\/app\/uploads\/sites\/7\/2026\/05\/IMG_0155-1024x768.jpeg","contentUrl":"https:\/\/www.stachristiana.at\/app\/uploads\/sites\/7\/2026\/05\/IMG_0155-1024x768.jpeg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.stachristiana.at\/volksschule-rodaun\/news\/rueckblick-2025-26-mit-erasmus-auf-entdeckungsreise-in-griechenland.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Start","item":"https:\/\/www.stachristiana.at\/"},{"@type":"ListItem","position":2,"name":"R\u00fcckblick 2025\/26: Mit Erasmus+ auf Entdeckungsreise in Griechenland"}]},{"@type":"WebSite","@id":"https:\/\/www.stachristiana.at\/volksschule-rodaun\/#website","url":"https:\/\/www.stachristiana.at\/volksschule-rodaun\/","name":"Sta. Christiana - Private Volksschule Rodaun","description":"Schulen zum Leben","publisher":{"@id":"https:\/\/www.stachristiana.at\/volksschule-rodaun\/#organization"},"alternateName":"Sta. Christiana","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.stachristiana.at\/volksschule-rodaun\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.stachristiana.at\/volksschule-rodaun\/#organization","name":"Sta. Christiana - Private Volksschule Rodaun","alternateName":"Sta. Christiana","url":"https:\/\/www.stachristiana.at\/volksschule-rodaun\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.stachristiana.at\/volksschule-rodaun\/#\/schema\/logo\/image\/","url":"https:\/\/www.stachristiana.at\/app\/uploads\/sites\/7\/2022\/05\/logo-sta-christiana.png","contentUrl":"https:\/\/www.stachristiana.at\/app\/uploads\/sites\/7\/2022\/05\/logo-sta-christiana.png","width":1200,"height":491,"caption":"Sta. Christiana - Private Volksschule Rodaun"},"image":{"@id":"https:\/\/www.stachristiana.at\/volksschule-rodaun\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.stachristiana.at\/volksschule-rodaun\/#\/schema\/person\/145981df32740f5ce76015703024cf57","name":"teresaspiess","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/07fb5e28c564dbade850e52239d0e4c0317f92215405dd0f28a0468c307ad1ac?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/07fb5e28c564dbade850e52239d0e4c0317f92215405dd0f28a0468c307ad1ac?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/07fb5e28c564dbade850e52239d0e4c0317f92215405dd0f28a0468c307ad1ac?s=96&d=mm&r=g","caption":"teresaspiess"},"url":"https:\/\/www.stachristiana.at\/volksschule-rodaun\/author\/teresaspiess"}]}},"_links":{"self":[{"href":"https:\/\/www.stachristiana.at\/volksschule-rodaun\/wp-json\/wp\/v2\/posts\/1802","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.stachristiana.at\/volksschule-rodaun\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.stachristiana.at\/volksschule-rodaun\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.stachristiana.at\/volksschule-rodaun\/wp-json\/wp\/v2\/users\/79"}],"replies":[{"embeddable":true,"href":"https:\/\/www.stachristiana.at\/volksschule-rodaun\/wp-json\/wp\/v2\/comments?post=1802"}],"version-history":[{"count":1,"href":"https:\/\/www.stachristiana.at\/volksschule-rodaun\/wp-json\/wp\/v2\/posts\/1802\/revisions"}],"predecessor-version":[{"id":1811,"href":"https:\/\/www.stachristiana.at\/volksschule-rodaun\/wp-json\/wp\/v2\/posts\/1802\/revisions\/1811"}],"wp:attachment":[{"href":"https:\/\/www.stachristiana.at\/volksschule-rodaun\/wp-json\/wp\/v2\/media?parent=1802"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.stachristiana.at\/volksschule-rodaun\/wp-json\/wp\/v2\/categories?post=1802"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.stachristiana.at\/volksschule-rodaun\/wp-json\/wp\/v2\/tags?post=1802"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}