{"id":1209,"date":"2025-01-09T19:53:55","date_gmt":"2025-01-09T18:53:55","guid":{"rendered":"https:\/\/www.stachristiana.at\/volksschule-rodaun\/?p=1209"},"modified":"2025-02-17T20:38:49","modified_gmt":"2025-02-17T19:38:49","slug":"unsere-dritten-klassen-machen-die-piste-unsicher","status":"publish","type":"post","link":"https:\/\/www.stachristiana.at\/volksschule-rodaun\/news\/unsere-dritten-klassen-machen-die-piste-unsicher.html","title":{"rendered":"Unsere dritten Klassen machen die Skipiste unsicher"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Ganz gleich, ob Pizzaschnitte oder Pommes, der Skitag der dritten Klassen war ein aufregendes Abenteuer im Schnee. Einige Sch\u00fclerinnen und Sch\u00fcler hatten zum ersten Mal die Gelegenheit, sich auf den Skiern zu versuchen, andere wiederum wedelten die steile Piste bereits in weiten Schw\u00fcngen hinunter.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Zur Mittagszeit konnten wir uns auf der Bergh\u00fctte ausgiebig st\u00e4rken, bevor die Skier nachmittags wieder angeschnallt wurden. Gemeinsam mit der Unterst\u00fctzung der Skilehrer:innen sowie Lehrk\u00f6rper verbrachte das gesamte Team einen Tag voller Spa\u00df, Spiel und Bewegung an der frischen Luft.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/www.stachristiana.at\/app\/uploads\/sites\/7\/2025\/01\/WhatsApp-Image-2025-02-17-at-17.43.45-1-1024x576.jpeg\" alt=\"\" class=\"wp-image-1216\" srcset=\"https:\/\/www.stachristiana.at\/app\/uploads\/sites\/7\/2025\/01\/WhatsApp-Image-2025-02-17-at-17.43.45-1-1024x576.jpeg 1024w, https:\/\/www.stachristiana.at\/app\/uploads\/sites\/7\/2025\/01\/WhatsApp-Image-2025-02-17-at-17.43.45-1-400x225.jpeg 400w, https:\/\/www.stachristiana.at\/app\/uploads\/sites\/7\/2025\/01\/WhatsApp-Image-2025-02-17-at-17.43.45-1-768x432.jpeg 768w, https:\/\/www.stachristiana.at\/app\/uploads\/sites\/7\/2025\/01\/WhatsApp-Image-2025-02-17-at-17.43.45-1-1536x864.jpeg 1536w, https:\/\/www.stachristiana.at\/app\/uploads\/sites\/7\/2025\/01\/WhatsApp-Image-2025-02-17-at-17.43.45-1-818x460.jpeg 818w, https:\/\/www.stachristiana.at\/app\/uploads\/sites\/7\/2025\/01\/WhatsApp-Image-2025-02-17-at-17.43.45-1-133x75.jpeg 133w, https:\/\/www.stachristiana.at\/app\/uploads\/sites\/7\/2025\/01\/WhatsApp-Image-2025-02-17-at-17.43.45-1.jpeg 2016w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Ganz gleich, ob Pizzaschnitte oder Pommes, der Skitag der dritten Klassen war ein aufregendes Abenteuer im Schnee. Einige Sch\u00fclerinnen und Sch\u00fcler hatten zum ersten Mal die Gelegenheit, sich auf den Skiern zu versuchen, andere wiederum wedelten die steile Piste bereits in weiten Schw\u00fcngen hinunter. Zur Mittagszeit konnten wir uns auf der Bergh\u00fctte ausgiebig st\u00e4rken, bevor [&hellip;]<\/p>\n","protected":false},"author":79,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1209","post","type-post","status-publish","format-standard","hentry","category-news"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Unsere dritten Klassen machen die Skipiste unsicher - Volksschule Rodaun<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.stachristiana.at\/volksschule-rodaun\/news\/unsere-dritten-klassen-machen-die-piste-unsicher.html\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Unsere dritten Klassen machen die Skipiste unsicher - Volksschule Rodaun\" \/>\n<meta property=\"og:description\" content=\"Ganz gleich, ob Pizzaschnitte oder Pommes, der Skitag der dritten Klassen war ein aufregendes Abenteuer im Schnee. Einige Sch\u00fclerinnen und Sch\u00fcler hatten zum ersten Mal die Gelegenheit, sich auf den Skiern zu versuchen, andere wiederum wedelten die steile Piste bereits in weiten Schw\u00fcngen hinunter. Zur Mittagszeit konnten wir uns auf der Bergh\u00fctte ausgiebig st\u00e4rken, bevor [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.stachristiana.at\/volksschule-rodaun\/news\/unsere-dritten-klassen-machen-die-piste-unsicher.html\" \/>\n<meta property=\"og:site_name\" content=\"Volksschule Rodaun\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-09T18:53:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-17T19:38:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.stachristiana.at\/app\/uploads\/sites\/7\/2025\/01\/WhatsApp-Image-2025-02-17-at-17.43.45-1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2016\" \/>\n\t<meta property=\"og:image:height\" content=\"1134\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"teresaspiess\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"teresaspiess\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.stachristiana.at\\\/volksschule-rodaun\\\/news\\\/unsere-dritten-klassen-machen-die-piste-unsicher.html#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.stachristiana.at\\\/volksschule-rodaun\\\/news\\\/unsere-dritten-klassen-machen-die-piste-unsicher.html\"},\"author\":{\"name\":\"teresaspiess\",\"@id\":\"https:\\\/\\\/www.stachristiana.at\\\/volksschule-rodaun\\\/#\\\/schema\\\/person\\\/145981df32740f5ce76015703024cf57\"},\"headline\":\"Unsere dritten Klassen machen die Skipiste unsicher\",\"datePublished\":\"2025-01-09T18:53:55+00:00\",\"dateModified\":\"2025-02-17T19:38:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.stachristiana.at\\\/volksschule-rodaun\\\/news\\\/unsere-dritten-klassen-machen-die-piste-unsicher.html\"},\"wordCount\":99,\"publisher\":{\"@id\":\"https:\\\/\\\/www.stachristiana.at\\\/volksschule-rodaun\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.stachristiana.at\\\/volksschule-rodaun\\\/news\\\/unsere-dritten-klassen-machen-die-piste-unsicher.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.stachristiana.at\\\/app\\\/uploads\\\/sites\\\/7\\\/2025\\\/01\\\/WhatsApp-Image-2025-02-17-at-17.43.45-1-1024x576.jpeg\",\"articleSection\":[\"News\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.stachristiana.at\\\/volksschule-rodaun\\\/news\\\/unsere-dritten-klassen-machen-die-piste-unsicher.html\",\"url\":\"https:\\\/\\\/www.stachristiana.at\\\/volksschule-rodaun\\\/news\\\/unsere-dritten-klassen-machen-die-piste-unsicher.html\",\"name\":\"Unsere dritten Klassen machen die Skipiste unsicher - Volksschule Rodaun\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.stachristiana.at\\\/volksschule-rodaun\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.stachristiana.at\\\/volksschule-rodaun\\\/news\\\/unsere-dritten-klassen-machen-die-piste-unsicher.html#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.stachristiana.at\\\/volksschule-rodaun\\\/news\\\/unsere-dritten-klassen-machen-die-piste-unsicher.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.stachristiana.at\\\/app\\\/uploads\\\/sites\\\/7\\\/2025\\\/01\\\/WhatsApp-Image-2025-02-17-at-17.43.45-1-1024x576.jpeg\",\"datePublished\":\"2025-01-09T18:53:55+00:00\",\"dateModified\":\"2025-02-17T19:38:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.stachristiana.at\\\/volksschule-rodaun\\\/news\\\/unsere-dritten-klassen-machen-die-piste-unsicher.html#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.stachristiana.at\\\/volksschule-rodaun\\\/news\\\/unsere-dritten-klassen-machen-die-piste-unsicher.html\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.stachristiana.at\\\/volksschule-rodaun\\\/news\\\/unsere-dritten-klassen-machen-die-piste-unsicher.html#primaryimage\",\"url\":\"https:\\\/\\\/www.stachristiana.at\\\/app\\\/uploads\\\/sites\\\/7\\\/2025\\\/01\\\/WhatsApp-Image-2025-02-17-at-17.43.45-1-1024x576.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.stachristiana.at\\\/app\\\/uploads\\\/sites\\\/7\\\/2025\\\/01\\\/WhatsApp-Image-2025-02-17-at-17.43.45-1-1024x576.jpeg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.stachristiana.at\\\/volksschule-rodaun\\\/news\\\/unsere-dritten-klassen-machen-die-piste-unsicher.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Start\",\"item\":\"https:\\\/\\\/www.stachristiana.at\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Unsere dritten Klassen machen die Skipiste unsicher\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.stachristiana.at\\\/volksschule-rodaun\\\/#website\",\"url\":\"https:\\\/\\\/www.stachristiana.at\\\/volksschule-rodaun\\\/\",\"name\":\"Sta. Christiana - Private Volksschule Rodaun\",\"description\":\"Schulen zum Leben\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.stachristiana.at\\\/volksschule-rodaun\\\/#organization\"},\"alternateName\":\"Sta. Christiana\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.stachristiana.at\\\/volksschule-rodaun\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.stachristiana.at\\\/volksschule-rodaun\\\/#organization\",\"name\":\"Sta. Christiana - Private Volksschule Rodaun\",\"alternateName\":\"Sta. Christiana\",\"url\":\"https:\\\/\\\/www.stachristiana.at\\\/volksschule-rodaun\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.stachristiana.at\\\/volksschule-rodaun\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.stachristiana.at\\\/app\\\/uploads\\\/sites\\\/7\\\/2022\\\/05\\\/logo-sta-christiana.png\",\"contentUrl\":\"https:\\\/\\\/www.stachristiana.at\\\/app\\\/uploads\\\/sites\\\/7\\\/2022\\\/05\\\/logo-sta-christiana.png\",\"width\":1200,\"height\":491,\"caption\":\"Sta. Christiana - Private Volksschule Rodaun\"},\"image\":{\"@id\":\"https:\\\/\\\/www.stachristiana.at\\\/volksschule-rodaun\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.stachristiana.at\\\/volksschule-rodaun\\\/#\\\/schema\\\/person\\\/145981df32740f5ce76015703024cf57\",\"name\":\"teresaspiess\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/07fb5e28c564dbade850e52239d0e4c0317f92215405dd0f28a0468c307ad1ac?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/07fb5e28c564dbade850e52239d0e4c0317f92215405dd0f28a0468c307ad1ac?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/07fb5e28c564dbade850e52239d0e4c0317f92215405dd0f28a0468c307ad1ac?s=96&d=mm&r=g\",\"caption\":\"teresaspiess\"},\"url\":\"https:\\\/\\\/www.stachristiana.at\\\/volksschule-rodaun\\\/author\\\/teresaspiess\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Unsere dritten Klassen machen die Skipiste unsicher - Volksschule Rodaun","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.stachristiana.at\/volksschule-rodaun\/news\/unsere-dritten-klassen-machen-die-piste-unsicher.html","og_locale":"de_DE","og_type":"article","og_title":"Unsere dritten Klassen machen die Skipiste unsicher - Volksschule Rodaun","og_description":"Ganz gleich, ob Pizzaschnitte oder Pommes, der Skitag der dritten Klassen war ein aufregendes Abenteuer im Schnee. Einige Sch\u00fclerinnen und Sch\u00fcler hatten zum ersten Mal die Gelegenheit, sich auf den Skiern zu versuchen, andere wiederum wedelten die steile Piste bereits in weiten Schw\u00fcngen hinunter. Zur Mittagszeit konnten wir uns auf der Bergh\u00fctte ausgiebig st\u00e4rken, bevor [&hellip;]","og_url":"https:\/\/www.stachristiana.at\/volksschule-rodaun\/news\/unsere-dritten-klassen-machen-die-piste-unsicher.html","og_site_name":"Volksschule Rodaun","article_published_time":"2025-01-09T18:53:55+00:00","article_modified_time":"2025-02-17T19:38:49+00:00","og_image":[{"width":2016,"height":1134,"url":"https:\/\/www.stachristiana.at\/app\/uploads\/sites\/7\/2025\/01\/WhatsApp-Image-2025-02-17-at-17.43.45-1.jpeg","type":"image\/jpeg"}],"author":"teresaspiess","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"teresaspiess","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.stachristiana.at\/volksschule-rodaun\/news\/unsere-dritten-klassen-machen-die-piste-unsicher.html#article","isPartOf":{"@id":"https:\/\/www.stachristiana.at\/volksschule-rodaun\/news\/unsere-dritten-klassen-machen-die-piste-unsicher.html"},"author":{"name":"teresaspiess","@id":"https:\/\/www.stachristiana.at\/volksschule-rodaun\/#\/schema\/person\/145981df32740f5ce76015703024cf57"},"headline":"Unsere dritten Klassen machen die Skipiste unsicher","datePublished":"2025-01-09T18:53:55+00:00","dateModified":"2025-02-17T19:38:49+00:00","mainEntityOfPage":{"@id":"https:\/\/www.stachristiana.at\/volksschule-rodaun\/news\/unsere-dritten-klassen-machen-die-piste-unsicher.html"},"wordCount":99,"publisher":{"@id":"https:\/\/www.stachristiana.at\/volksschule-rodaun\/#organization"},"image":{"@id":"https:\/\/www.stachristiana.at\/volksschule-rodaun\/news\/unsere-dritten-klassen-machen-die-piste-unsicher.html#primaryimage"},"thumbnailUrl":"https:\/\/www.stachristiana.at\/app\/uploads\/sites\/7\/2025\/01\/WhatsApp-Image-2025-02-17-at-17.43.45-1-1024x576.jpeg","articleSection":["News"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.stachristiana.at\/volksschule-rodaun\/news\/unsere-dritten-klassen-machen-die-piste-unsicher.html","url":"https:\/\/www.stachristiana.at\/volksschule-rodaun\/news\/unsere-dritten-klassen-machen-die-piste-unsicher.html","name":"Unsere dritten Klassen machen die Skipiste unsicher - Volksschule Rodaun","isPartOf":{"@id":"https:\/\/www.stachristiana.at\/volksschule-rodaun\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.stachristiana.at\/volksschule-rodaun\/news\/unsere-dritten-klassen-machen-die-piste-unsicher.html#primaryimage"},"image":{"@id":"https:\/\/www.stachristiana.at\/volksschule-rodaun\/news\/unsere-dritten-klassen-machen-die-piste-unsicher.html#primaryimage"},"thumbnailUrl":"https:\/\/www.stachristiana.at\/app\/uploads\/sites\/7\/2025\/01\/WhatsApp-Image-2025-02-17-at-17.43.45-1-1024x576.jpeg","datePublished":"2025-01-09T18:53:55+00:00","dateModified":"2025-02-17T19:38:49+00:00","breadcrumb":{"@id":"https:\/\/www.stachristiana.at\/volksschule-rodaun\/news\/unsere-dritten-klassen-machen-die-piste-unsicher.html#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.stachristiana.at\/volksschule-rodaun\/news\/unsere-dritten-klassen-machen-die-piste-unsicher.html"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.stachristiana.at\/volksschule-rodaun\/news\/unsere-dritten-klassen-machen-die-piste-unsicher.html#primaryimage","url":"https:\/\/www.stachristiana.at\/app\/uploads\/sites\/7\/2025\/01\/WhatsApp-Image-2025-02-17-at-17.43.45-1-1024x576.jpeg","contentUrl":"https:\/\/www.stachristiana.at\/app\/uploads\/sites\/7\/2025\/01\/WhatsApp-Image-2025-02-17-at-17.43.45-1-1024x576.jpeg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.stachristiana.at\/volksschule-rodaun\/news\/unsere-dritten-klassen-machen-die-piste-unsicher.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Start","item":"https:\/\/www.stachristiana.at\/"},{"@type":"ListItem","position":2,"name":"Unsere dritten Klassen machen die Skipiste unsicher"}]},{"@type":"WebSite","@id":"https:\/\/www.stachristiana.at\/volksschule-rodaun\/#website","url":"https:\/\/www.stachristiana.at\/volksschule-rodaun\/","name":"Sta. Christiana - Private Volksschule Rodaun","description":"Schulen zum Leben","publisher":{"@id":"https:\/\/www.stachristiana.at\/volksschule-rodaun\/#organization"},"alternateName":"Sta. Christiana","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.stachristiana.at\/volksschule-rodaun\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.stachristiana.at\/volksschule-rodaun\/#organization","name":"Sta. Christiana - Private Volksschule Rodaun","alternateName":"Sta. Christiana","url":"https:\/\/www.stachristiana.at\/volksschule-rodaun\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.stachristiana.at\/volksschule-rodaun\/#\/schema\/logo\/image\/","url":"https:\/\/www.stachristiana.at\/app\/uploads\/sites\/7\/2022\/05\/logo-sta-christiana.png","contentUrl":"https:\/\/www.stachristiana.at\/app\/uploads\/sites\/7\/2022\/05\/logo-sta-christiana.png","width":1200,"height":491,"caption":"Sta. Christiana - Private Volksschule Rodaun"},"image":{"@id":"https:\/\/www.stachristiana.at\/volksschule-rodaun\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.stachristiana.at\/volksschule-rodaun\/#\/schema\/person\/145981df32740f5ce76015703024cf57","name":"teresaspiess","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/07fb5e28c564dbade850e52239d0e4c0317f92215405dd0f28a0468c307ad1ac?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/07fb5e28c564dbade850e52239d0e4c0317f92215405dd0f28a0468c307ad1ac?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/07fb5e28c564dbade850e52239d0e4c0317f92215405dd0f28a0468c307ad1ac?s=96&d=mm&r=g","caption":"teresaspiess"},"url":"https:\/\/www.stachristiana.at\/volksschule-rodaun\/author\/teresaspiess"}]}},"_links":{"self":[{"href":"https:\/\/www.stachristiana.at\/volksschule-rodaun\/wp-json\/wp\/v2\/posts\/1209","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.stachristiana.at\/volksschule-rodaun\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.stachristiana.at\/volksschule-rodaun\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.stachristiana.at\/volksschule-rodaun\/wp-json\/wp\/v2\/users\/79"}],"replies":[{"embeddable":true,"href":"https:\/\/www.stachristiana.at\/volksschule-rodaun\/wp-json\/wp\/v2\/comments?post=1209"}],"version-history":[{"count":4,"href":"https:\/\/www.stachristiana.at\/volksschule-rodaun\/wp-json\/wp\/v2\/posts\/1209\/revisions"}],"predecessor-version":[{"id":1217,"href":"https:\/\/www.stachristiana.at\/volksschule-rodaun\/wp-json\/wp\/v2\/posts\/1209\/revisions\/1217"}],"wp:attachment":[{"href":"https:\/\/www.stachristiana.at\/volksschule-rodaun\/wp-json\/wp\/v2\/media?parent=1209"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.stachristiana.at\/volksschule-rodaun\/wp-json\/wp\/v2\/categories?post=1209"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.stachristiana.at\/volksschule-rodaun\/wp-json\/wp\/v2\/tags?post=1209"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}